{"id":83,"date":"2019-12-23T20:19:11","date_gmt":"2019-12-23T19:19:11","guid":{"rendered":"https:\/\/www.redegold.de\/shop\/widerruf\/"},"modified":"2026-07-07T09:19:31","modified_gmt":"2026-07-07T07:19:31","slug":"widerruf","status":"publish","type":"page","link":"https:\/\/www.redegold.de\/shop\/widerruf\/","title":{"rendered":"Widerruf"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.88%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><\/p>\n<h1>Widerrufsbelehrung<\/h1>\n<p>Verbrauchern steht das nachfolgende Widerrufsrecht zu. Bitte beachten Sie: Je nachdem, ob Sie eine <strong>Dienstleistung<\/strong> (z. B. Redetexte, Redenoptimierung, Rede-Consulting, Trainings) oder eine <strong>Ware<\/strong> (z. B. Druckerzeugnisse) bestellt haben, gilt die jeweils zutreffende Belehrung. F\u00fcr individuell nach Ihren Vorgaben angefertigte Waren besteht kein Widerrufsrecht (siehe Hinweis am Ende dieser Seite).<\/p>\n<h2>A. Widerrufsbelehrung f\u00fcr Dienstleistungen<\/h2>\n<p><em>(z. B. Erstellung und Optimierung von Redetexten, Rede-Consulting, Trainings, Audiodateien und sonstige Dienstleistungen)<\/em><\/p>\n<h3>Widerrufsrecht<\/h3>\n<p>Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen.<\/p>\n<p>Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag des Vertragsschlusses.<\/p>\n<p>Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns<\/p>\n<p>RedeGold Redenschreiber Frank Rosenbauer M. A. &amp; Co-Autoren<br \/>Altenhof 9<br \/>57074 Siegen, Deutschland<br \/>Telefon: +49-271-2229452-1<br \/>Telefax: +49-271-2229452-9<br \/>E-Mail: frank.rosenbauer@redegold.de<\/p>\n<p>mittels einer eindeutigen Erkl\u00e4rung (z. B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist.<\/p>\n<p>Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<h3>Folgen des Widerrufs<\/h3>\n<p>Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<\/p>\n<p>Haben Sie verlangt, dass die Dienstleistungen w\u00e4hrend der Widerrufsfrist beginnen sollen, so haben Sie uns einen angemessenen Betrag zu zahlen, der dem Anteil der bis zu dem Zeitpunkt, zu dem Sie uns von der Aus\u00fcbung des Widerrufsrechts hinsichtlich dieses Vertrags unterrichten, bereits erbrachten Dienstleistungen im Vergleich zum Gesamtumfang der im Vertrag vorgesehenen Dienstleistungen entspricht.<\/p>\n<h3>Erl\u00f6schen des Widerrufsrechts<\/h3>\n<p>Das Widerrufsrecht erlischt vorzeitig, wenn wir die Dienstleistung vollst\u00e4ndig erbracht haben und mit der Ausf\u00fchrung der Dienstleistung erst begonnen haben, nachdem Sie dazu Ihre ausdr\u00fcckliche Zustimmung gegeben und gleichzeitig Ihre Kenntnis davon best\u00e4tigt haben, dass Sie Ihr Widerrufsrecht bei vollst\u00e4ndiger Vertragserf\u00fcllung durch uns verlieren.<\/p>\n<h2>B. Widerrufsbelehrung f\u00fcr die Lieferung von Waren<\/h2>\n<p><em>(z. B. Druckerzeugnisse, soweit nicht individuell nach Kundenspezifikation angefertigt \u2013 siehe Hinweis unter C.)<\/em><\/p>\n<h3>Widerrufsrecht<\/h3>\n<p>Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen.<\/p>\n<p>Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat.<\/p>\n<p>Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns<\/p>\n<p>RedeGold Redenschreiber Frank Rosenbauer M. A. &amp; Co-Autoren<br \/>Altenhof 9<br \/>57074 Siegen, Deutschland<br \/>Telefon: +49-271-2229452-1<br \/>Telefax: +49-271-2229452-9<br \/>E-Mail: frank.rosenbauer@redegold.de<\/p>\n<p>mittels einer eindeutigen Erkl\u00e4rung (z. B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist.<\/p>\n<p>Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<h3>Folgen des Widerrufs<\/h3>\n<p>Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<\/p>\n<p>Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.<\/p>\n<p>Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<\/p>\n<p>Sie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<\/p>\n<p>Sie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<h2>C. Ausschluss des Widerrufsrechts<\/h2>\n<p>Das Widerrufsrecht besteht nicht bei Vertr\u00e4gen zur Lieferung von Waren, die nicht vorgefertigt sind und f\u00fcr deren Herstellung eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind (\u00a7 312g Abs. 2 Nr. 1 BGB).<\/p>\n<p>Dies betrifft insbesondere unsere individuellen Druckerzeugnisse, die mit Ihrem Redetext oder sonstigen von Ihnen bestimmten Inhalten bedruckt werden (z. B. Redekarten, Schmuckdruck, vortragssicherer Druck).<\/p>\n<h2>Muster-Widerrufsformular<\/h2>\n<p>(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<\/p>\n<p>An:<br \/>RedeGold Redenschreiber Frank Rosenbauer M. A. &amp; Co-Autoren<br \/>Altenhof 9<br \/>57074 Siegen, Deutschland<br \/>E-Mail: frank.rosenbauer@redegold.de<\/p>\n<p>\u2013 Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)\/die Erbringung der folgenden Dienstleistung (*):<\/p>\n<p>_______________________<\/p>\n<p>\u2013 Bestellt am (*)\/erhalten am (*): _______________________<\/p>\n<p>\u2013 Name des\/der Verbraucher(s): _______________________<\/p>\n<p>\u2013 Anschrift des\/der Verbraucher(s): _______________________<\/p>\n<p>\u2013 Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier): _______________________<\/p>\n<p>\u2013 Datum: _______________________<\/p>\n<p>(*) Unzutreffendes streichen.<\/p>\n<p>Stand: 7. Juli 2026<\/p><\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"class_list":["post-83","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.redegold.de\/shop\/wp-json\/wp\/v2\/pages\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redegold.de\/shop\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.redegold.de\/shop\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.redegold.de\/shop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redegold.de\/shop\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":0,"href":"https:\/\/www.redegold.de\/shop\/wp-json\/wp\/v2\/pages\/83\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redegold.de\/shop\/wp-json\/wp\/v2\/media?parent=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}